{"id":86,"date":"2017-02-11T15:43:43","date_gmt":"2017-02-11T14:43:43","guid":{"rendered":"http:\/\/www.znaim.info\/blog\/?p=86"},"modified":"2026-03-10T10:45:08","modified_gmt":"2026-03-10T09:45:08","slug":"unbekannte-matrik-aufgetaucht","status":"publish","type":"post","link":"http:\/\/www.znaim.info\/blog\/index.php\/2017\/02\/11\/unbekannte-matrik-aufgetaucht\/","title":{"rendered":"Unbekannte Matrik aufgetaucht"},"content":{"rendered":"<p>Es geschehen noch Zeichen und Wunder! Zwar ist dieses hier bereits vor 30 Jahren geschehen, aber ich m\u00f6chte dennoch an dieser Stelle daran erinnern. Normalerweise ist man daran gew\u00f6hnt, da\u00df zahlreiche Archivalien, die in alten Inventaren aufgef\u00fchrt sind, nicht mehr existieren oder zumindest nicht mehr auffindbar sind. Zuweilen tauchen verloren geglaubte Quellen wieder auf, und auch bisher Unbekanntes tritt nach wie vor zu Tage &#8211; manchmal ist es allerdings so unbekannt, da\u00df man es kaum glauben mag: Im Jahre 1987 erwarb das M\u00e4hrische Landesarchiv bei einem Antiquariat in M\u00e4hrisch Ostrau (Ostrava) eine bisher unbekannte Matrik der Pfarre Hosterlitz (Host\u011bradice). Sie umfa\u00dft 149 Bl\u00e4tter und enth\u00e4lt Eintr\u00e4ge zu Taufen f\u00fcr die Jahre 1656-1677, Trauungen f\u00fcr\u00a0 1654-1678, und Begr\u00e4bnisse f\u00fcr 1653. In einer erhalten gebliebenen Auflistung des Dekanats Hosterlitz vom Jahre 1804 \u00fcber die damals vorhandenen Matriken scheint dieses Buch nicht auf &#8211; es war also mindestens 183 Jahre lang &#8222;nicht am Platz&#8220;. Wo es in der Zwischenzeit gewesen sein mag, w\u00e4re interessant zu erfahren. Sein Auftauchen jedenfalls ist ein Gl\u00fcck f\u00fcr die Forschung in der Znaimer Gegend, enth\u00e4lt das Buch doch &#8211; wie zahlreiche andere fr\u00fche Matriken der Region &#8211; Eintr\u00e4ge aus einem recht weiten lokalen Umfeld.<\/p>\n<p>Im Sytem von actapublica ist das Buch leider falsch eingeordnet, da der im maschinenschriftlichen Inventar eingef\u00fcgte Zettel, auf dem diese Matrik nachgetragen ist, bei der Digitalisierung offenbar f\u00e4lschlich der vorangehenden Pfarre Horn\u00ed Kounice zugeordnet wurde (<a href=\"http:\/\/actapublica.eu\/matriky\/brno\/detail\/1377\/\" target=\"_blank\">http:\/\/actapublica.eu\/matriky\/brno\/detail\/1377\/<\/a>), dies tut aber dem dankenswerten Umstand keinen Abbruch, da\u00df sich wie die anderen Matriken des MZA Brno auch dieses Buch mit seiner au\u00dfergew\u00f6hnlichen Provenienzgeschichte bequem online betrachten l\u00e4\u00dft: <a href=\"http:\/\/actapublica.eu\/matriky\/brno\/prohlizec\/1377\/?strana=1\" target=\"_blank\">http:\/\/actapublica.eu\/matriky\/brno\/prohlizec\/1377\/?strana=1<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es geschehen noch Zeichen und Wunder! Zwar ist dieses hier bereits vor 30 Jahren geschehen, aber ich m\u00f6chte dennoch an dieser Stelle daran erinnern. Normalerweise ist man daran gew\u00f6hnt, da\u00df zahlreiche Archivalien, die in alten Inventaren aufgef\u00fchrt sind, nicht mehr existieren oder zumindest nicht mehr auffindbar sind. Zuweilen tauchen verloren geglaubte Quellen wieder auf, und &hellip; <a href=\"http:\/\/www.znaim.info\/blog\/index.php\/2017\/02\/11\/unbekannte-matrik-aufgetaucht\/\" class=\"more-link\"><span class=\"screen-reader-text\">Unbekannte Matrik aufgetaucht<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":5,"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"predecessor-version":[{"id":128,"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/posts\/86\/revisions\/128"}],"wp:attachment":[{"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.znaim.info\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}